{"id":11300,"date":"2020-12-08T10:50:18","date_gmt":"2020-12-08T09:50:18","guid":{"rendered":"https:\/\/www.photocontestclub.org\/?page_id=11300"},"modified":"2021-04-27T17:04:12","modified_gmt":"2021-04-27T15:04:12","slug":"roberto-filomena-nw20","status":"publish","type":"page","link":"https:\/\/www.photocontestclub.org\/it\/roberto-filomena-nw20\/","title":{"rendered":"ROBERTO FILOMENA NW20"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11300\" class=\"elementor elementor-11300\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fdda19b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fdda19b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2311ef50\" data-id=\"2311ef50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36dd39f7 elementor-widget elementor-widget-text-editor\" data-id=\"36dd39f7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-text-editor elementor-clearfix\"><h2>ROBERTO FILOMENA NW20<\/h2><\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d0961f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d0961f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef03ae1\" data-id=\"ef03ae1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06c6b98 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"06c6b98\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd8ae91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd8ae91\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5829cb8\" data-id=\"5829cb8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f79dc0e elementor-widget elementor-widget-icon-list\" data-id=\"f79dc0e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <ul class=\"elementor-icon-list-items elementor-inline-items\">\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"opal-icon-account\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\"><\/span>\n                                    <\/li>\n                            <li class=\"elementor-icon-list-item\" >\n                    <a href=\"https:\/\/www.facebook.com\/roberto.filomena.3\">                        <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-facebook-official\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Facebook<\/span>\n                                            <\/a>\n                                    <\/li>\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-instagram\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Instagram<\/span>\n                                    <\/li>\n                    <\/ul>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7d5d5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7d5d5d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-defdb58\" data-id=\"defdb58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d04b40 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3d04b40\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c48a19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c48a19\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29a809a\" data-id=\"29a809a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a49621 elementor-widget elementor-widget-text-editor\" data-id=\"1a49621\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-text-editor elementor-clearfix\"><p>[ngg src=&#8221;galleries&#8221; ids=&#8221;175&#8243; display=&#8221;basic_thumbnail&#8221; thumbnail_crop=&#8221;0&#8243;]<\/p><\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ROBERTO FILOMENA NW20 Facebook Instagram [ngg src=&#8221;galleries&#8221; ids=&#8221;175&#8243; display=&#8221;basic_thumbnail&#8221; thumbnail_crop=&#8221;0&#8243;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":1000,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ROBERTO FILOMENA NW20 - Photo Contest Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.photocontestclub.org\/it\/roberto-filomena-nw20\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ROBERTO FILOMENA NW20 - Photo Contest Club\" \/>\n<meta property=\"og:description\" content=\"ROBERTO FILOMENA NW20 Facebook Instagram [ngg src=&#8221;galleries&#8221; ids=&#8221;175&#8243; display=&#8221;basic_thumbnail&#8221; thumbnail_crop=&#8221;0&#8243;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.photocontestclub.org\/it\/roberto-filomena-nw20\/\" \/>\n<meta property=\"og:site_name\" content=\"Photo Contest Club\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T15:04:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\">\n\t<meta name=\"twitter:data1\" content=\"Silvano\">\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data2\" content=\"0 minuti\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.photocontestclub.org\/it\/#website\",\"url\":\"https:\/\/www.photocontestclub.org\/it\/\",\"name\":\"Photo Contest Club\",\"description\":\"Associazione\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.photocontestclub.org\/it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.photocontestclub.org\/it\/roberto-filomena-nw20\/#webpage\",\"url\":\"https:\/\/www.photocontestclub.org\/it\/roberto-filomena-nw20\/\",\"name\":\"ROBERTO FILOMENA NW20 - Photo Contest Club\",\"isPartOf\":{\"@id\":\"https:\/\/www.photocontestclub.org\/it\/#website\"},\"datePublished\":\"2020-12-08T09:50:18+00:00\",\"dateModified\":\"2021-04-27T15:04:12+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.photocontestclub.org\/it\/roberto-filomena-nw20\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages\/11300"}],"collection":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/comments?post=11300"}],"version-history":[{"count":4,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages\/11300\/revisions"}],"predecessor-version":[{"id":11304,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages\/11300\/revisions\/11304"}],"wp:attachment":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/media?parent=11300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}