{"id":2069,"date":"2019-09-05T08:33:25","date_gmt":"2019-09-05T06:33:25","guid":{"rendered":"http:\/\/dev.wpopal.com\/costix\/our-team-3\/"},"modified":"2020-10-29T18:14:55","modified_gmt":"2020-10-29T17:14:55","slug":"our-team-3","status":"publish","type":"page","link":"https:\/\/www.photocontestclub.org\/it\/our-team-3\/","title":{"rendered":"Our Team 3"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2069\" class=\"elementor elementor-2069\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0a575e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"e0a575e\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc3178f\" data-id=\"bc3178f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6a2c33 elementor-align-center elementor-widget elementor-widget-heading\" data-id=\"c6a2c33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Awesome people<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d10330 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"2d10330\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-19ff236\" data-id=\"19ff236\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdc448b elementor-widget elementor-widget-opal-team-box\" data-id=\"cdc448b\" data-element_type=\"widget\" data-widget_type=\"opal-team-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-teams-wrapper elementor-team-style3\">\n            <div class=\"elementor-team-item\">\n                        <div class=\"elementor-team-meta-inner\">\n            <div class=\"elementor-team-image\">\n                <img src=\"https:\/\/www.photocontestclub.org\/wp-content\/uploads\/elementor\/thumbs\/ourteam02_ava1-ow37xzc7kwxkpfautgud6u2r5rijgg576w5jyjwupo.png\" title=\"ourteam02_ava1\" alt=\"ourteam02_ava1\" \/>                                <div class=\"elementor-team-socials\">\n                                    <ul class=\"team-icon-socials\">\n                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                        <i class=\"fab fa-facebook\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                <li class=\"social\">\n                                    <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                        <i class=\"fab fa-twitter\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/plus.google.com\/u\/0\/+WPOpal\">\n                                        <i class=\"fab fa-google-plus\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                        <\/ul>\n                <\/div>\n            <\/div>\n                        <div class=\"elementor-team-details\">\n                <div class=\"elementor-team-name\">Bonnie Bowers <\/div>\n                <div class=\"elementor-team-job\">Chairman & CEO<\/div>\n            <\/div>\n                    <\/div>\n                    <\/div>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cacbbed\" data-id=\"cacbbed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf031fa elementor-widget elementor-widget-opal-team-box\" data-id=\"bf031fa\" data-element_type=\"widget\" data-widget_type=\"opal-team-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-teams-wrapper elementor-team-style3\">\n            <div class=\"elementor-team-item\">\n                        <div class=\"elementor-team-meta-inner\">\n            <div class=\"elementor-team-image\">\n                <img src=\"https:\/\/www.photocontestclub.org\/wp-content\/uploads\/elementor\/thumbs\/ourteam02_ava2-ow37xzc7kwxkpfautgud6u2r5rijgg576w5jyjwupo.png\" title=\"ourteam02_ava2\" alt=\"ourteam02_ava2\" \/>                                <div class=\"elementor-team-socials\">\n                                    <ul class=\"team-icon-socials\">\n                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                        <i class=\"fab fa-facebook\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                <li class=\"social\">\n                                    <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                        <i class=\"fab fa-twitter\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/plus.google.com\/u\/0\/+WPOpal\">\n                                        <i class=\"fab fa-google-plus\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                        <\/ul>\n                <\/div>\n            <\/div>\n                        <div class=\"elementor-team-details\">\n                <div class=\"elementor-team-name\">Angel May <\/div>\n                <div class=\"elementor-team-job\">Chief Financial Officer<\/div>\n            <\/div>\n                    <\/div>\n                    <\/div>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7bf11dd\" data-id=\"7bf11dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04088ab elementor-widget elementor-widget-opal-team-box\" data-id=\"04088ab\" data-element_type=\"widget\" data-widget_type=\"opal-team-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-teams-wrapper elementor-team-style3\">\n            <div class=\"elementor-team-item\">\n                        <div class=\"elementor-team-meta-inner\">\n            <div class=\"elementor-team-image\">\n                <img src=\"https:\/\/www.photocontestclub.org\/wp-content\/uploads\/elementor\/thumbs\/ourteam02_ava3-ow37y0a1rqyv119hnz8zrbu7r5dwo58xj0t1ftvgjg.png\" title=\"ourteam02_ava3\" alt=\"ourteam02_ava3\" \/>                                <div class=\"elementor-team-socials\">\n                                    <ul class=\"team-icon-socials\">\n                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                        <i class=\"fab fa-facebook\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                <li class=\"social\">\n                                    <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                        <i class=\"fab fa-twitter\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/plus.google.com\/u\/0\/+WPOpal\">\n                                        <i class=\"fab fa-google-plus\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                        <\/ul>\n                <\/div>\n            <\/div>\n                        <div class=\"elementor-team-details\">\n                <div class=\"elementor-team-name\">Abraham Anderson <\/div>\n                <div class=\"elementor-team-job\">Executive Vice President<\/div>\n            <\/div>\n                    <\/div>\n                    <\/div>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-78eb4ca\" data-id=\"78eb4ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b547f85 elementor-widget elementor-widget-opal-team-box\" data-id=\"b547f85\" data-element_type=\"widget\" data-widget_type=\"opal-team-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-teams-wrapper elementor-team-style3\">\n            <div class=\"elementor-team-item\">\n                        <div class=\"elementor-team-meta-inner\">\n            <div class=\"elementor-team-image\">\n                <img src=\"http:\/\/dev.wpopal.com\/costix\/wp-content\/uploads\/2019\/09\/ourteam02_ava4.png\" title=\"\" alt=\"\" \/>                                <div class=\"elementor-team-socials\">\n                                    <ul class=\"team-icon-socials\">\n                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                        <i class=\"fab fa-facebook\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                <li class=\"social\">\n                                    <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                        <i class=\"fab fa-twitter\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                                                                                                                    <li class=\"social\">\n                                    <a href=\"https:\/\/plus.google.com\/u\/0\/+WPOpal\">\n                                        <i class=\"fab fa-google-plus\"><\/i>\n                                    <\/a>\n                                <\/li>\n                                                                        <\/ul>\n                <\/div>\n            <\/div>\n                        <div class=\"elementor-team-details\">\n                <div class=\"elementor-team-name\">Preston Griffith <\/div>\n                <div class=\"elementor-team-job\">Chief Information Officer<\/div>\n            <\/div>\n                    <\/div>\n                    <\/div>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97325ca elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"97325ca\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c179ef4\" data-id=\"c179ef4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28eecaf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"28eecaf\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a55b613 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a55b613\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb5da6c\" data-id=\"cb5da6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aef04a elementor-align-center elementor-widget elementor-widget-heading\" data-id=\"3aef04a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"sub-title\">Ready To Get Start<\/span><h2 class=\"elementor-heading-title elementor-size-default\">Join thousands of users who boost <br\/>ntheir business with Costix<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d57de1 elementor-align-center elementor-button-primary elementor-widget elementor-widget-button\" data-id=\"3d57de1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-button-wrapper\">\n            <a href=\"#\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n                \t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact Us<\/span>\n\t\t<\/span>\n\t\t            <\/a>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23cb379 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"23cb379\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04ea961\" data-id=\"04ea961\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12006e6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"12006e6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":100,"comment_status":"closed","ping_status":"closed","template":"page-elementor.php","meta":{"inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Our Team 3 - Photo Contest Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.photocontestclub.org\/it\/our-team-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our Team 3 - Photo Contest Club\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.photocontestclub.org\/it\/our-team-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Photo Contest Club\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-29T17:14:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\">\n\t<meta name=\"twitter:data1\" content=\"admin_photocontest\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.photocontestclub.org\/it\/#website\",\"url\":\"https:\/\/www.photocontestclub.org\/it\/\",\"name\":\"Photo Contest Club\",\"description\":\"Associazione\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.photocontestclub.org\/it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.photocontestclub.org\/it\/our-team-3\/#webpage\",\"url\":\"https:\/\/www.photocontestclub.org\/it\/our-team-3\/\",\"name\":\"Our Team 3 - Photo Contest Club\",\"isPartOf\":{\"@id\":\"https:\/\/www.photocontestclub.org\/it\/#website\"},\"datePublished\":\"2019-09-05T06:33:25+00:00\",\"dateModified\":\"2020-10-29T17:14:55+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.photocontestclub.org\/it\/our-team-3\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages\/2069"}],"collection":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/comments?post=2069"}],"version-history":[{"count":1,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages\/2069\/revisions"}],"predecessor-version":[{"id":6876,"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/pages\/2069\/revisions\/6876"}],"wp:attachment":[{"href":"https:\/\/www.photocontestclub.org\/it\/wp-json\/wp\/v2\/media?parent=2069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}